{"id":7804,"date":"2023-04-15T13:25:05","date_gmt":"2023-04-15T17:25:05","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=7804"},"modified":"2023-05-09T17:29:18","modified_gmt":"2023-05-09T21:29:18","slug":"oscar-de-la-hoya-predice-las-posibles-compras-de-pay-per-view-para-jake-paul-vs-nate-diaz","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/oscar-de-la-hoya-predice-las-posibles-compras-de-pay-per-view-para-jake-paul-vs-nate-diaz\/","title":{"rendered":"Oscar De La Hoya predice las posibles compras de pay-per-view para Jake Paul vs. Nate Diaz"},"content":{"rendered":"<p><span>La leyenda del boxeo y promotor de peleas <strong>Oscar De La Hoya<\/strong> dio sus predicciones sobre las posibles compras de pay-per-view para <a href=\"\/tag\/Jake-Paul\"><strong>Jake Paul<\/strong><\/a> vs. <a href=\"\/tag\/Nate-Diaz\"><strong>Nate Diaz<\/strong><\/a>.\u00a0<\/span><span>Seg\u00fan &#8216;The Golden Boy&#8217;, el evento, organizado por <strong>DAZN Boxing<\/strong>, generar\u00e1 alrededor de 3 millones de d\u00f3lares en compras <a href=\"\/tag\/PPV\"><strong>PPV<\/strong><\/a>.<\/span><\/p>\n<p>Esto es lo que dijo el boxeador mexicano-estadounidense 11 veces campe\u00f3n mundial:<\/p>\n<blockquote><p>&#8220;Creo que puede ser una s\u00faper pelea, con Nate y Jake Paul, ya sabes, porque ambos saben c\u00f3mo pelear. Y Jake puede pelear. Nate es un verdadero peleador, sabe boxear y Jake Paul est\u00e1 haciendo lo suyo. Entonces, s\u00ed, hola Nate, si necesitas un promotor y necesitas ayuda, estoy aqu\u00ed dispuesto a hacer lo que sea&#8221;.<\/p><\/blockquote>\n<p><em><span>Mira las opiniones de Oscar De La Hoya sobre la pelea a trav\u00e9s de <a href=\"https:\/\/youtu.be\/olU9Ae60pHE\" target=\"_blank\" rel=\"noopener\"><strong>Inside Fighting<\/strong><\/a>:<\/span><\/em><\/p>\n<p><iframe title=\"Oscar De La Hoya predicted Nate Diaz vs Jake Paul will do 3 million PPV buys\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/olU9Ae60pHE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p><span>Despu\u00e9s de saludar a\u00a0<\/span><strong>Nate Diaz<\/strong><span>\u00a0con una oferta para ayudarlo a promocionarlo, De La Hoya pas\u00f3 a dar su opini\u00f3n sobre cu\u00e1nto generar\u00eda el evento en ventas de <strong>PPV<\/strong>.\u00a0Esto es lo que dijo &#8216;The Golden Boy&#8217;:<\/span><\/p>\n<blockquote><p>&#8220;Una pelea de Nate con Jake Paul ser\u00eda jodidamente enorme, enorme. Creo que [las compras de PPV] podr\u00edan ser como 2.5 a tres millones de pay-per-views, absolutamente&#8221;.<\/p><\/blockquote>\n<p><span>Cuando se le pregunt\u00f3 qui\u00e9n ganar\u00eda la pelea, Oscar De La Hoya dijo que cree que es una &#8216;pelea pareja&#8217;.\u00a0&#8216;The Golden Boy&#8217; piensa que\u00a0<\/span><strong>Jake Paul<\/strong><span> podr\u00eda tener m\u00e1s poder simplemente porque es &#8216;el tipo m\u00e1s grande&#8217;.\u00a0Sin embargo, De La Hoya tambi\u00e9n aludi\u00f3 a las habilidades t\u00e9cnicas y la efusividad\u00a0de D\u00edaz como boxeador, que es un estilo problem\u00e1tico incluso para los delanteros m\u00e1s condecorados.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La leyenda del boxeo y promotor de peleas Oscar De La Hoya dio sus predicciones sobre las posibles compras de pay-per-view para Jake Paul vs. Nate Diaz.\u00a0Seg\u00fan &#8216;The Golden Boy&#8217;, el evento, organizado por DAZN Boxing, generar\u00e1 alrededor de 3 millones de d\u00f3lares en compras PPV. Esto es lo que dijo el boxeador mexicano-estadounidense 11 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7805,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[350,300],"tags":[316,866,930,765],"class_list":["post-7804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxeo","category-noticias-de-mma","tag-jake-paul","tag-nate-diaz","tag-oscar-de-la-hoya","tag-ppv"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/04\/Oscar-de-la-Hoya-realizo-una-importante-donacion-para-los-pacientes-con-cancer-de-mama..webp?fit=1200%2C800&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/7804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=7804"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/7804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/7805"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=7804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=7804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=7804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}