{"id":7276,"date":"2023-04-09T01:30:07","date_gmt":"2023-04-09T05:30:07","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=7276"},"modified":"2023-06-05T21:56:16","modified_gmt":"2023-06-06T01:56:16","slug":"ufc-287-adesanya-cobra-venganza-sobre-pereira-con-fulminante-nocaut-en-el-segundo-asalto","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/ufc-287-adesanya-cobra-venganza-sobre-pereira-con-fulminante-nocaut-en-el-segundo-asalto\/","title":{"rendered":"UFC 287: Adesanya cobra venganza sobre Pereira con fulminante nocaut en el segundo asalto"},"content":{"rendered":"<p>El cintur\u00f3n de Peso Mediano de <a href=\"\/es\/tag\/ufc\/\"><strong>UFC<\/strong><\/a> regresa a las vitrinas de <strong>City Kickboxing<\/strong>.<\/p>\n<p><a href=\"\/es\/tag\/israel-adesanya\/\"><strong>Israel Adesanya<\/strong><\/a> se sac\u00f3 la espina m\u00e1s grande de su carrera en la estelar del <a href=\"\/es\/tag\/ufc-287\/\"><strong>UFC 287<\/strong><\/a> noqueando en dos asaltos a su verdugo m\u00e1s grande de los deportes de contacto: Alex Pereira.<\/p>\n<p>Adesanya, quien hab\u00eda quedado a segundos de finalizar al brasile\u00f1o en su primera pelea en las MMA, replic\u00f3 la misma secuencia de aquella ocasi\u00f3n: un volado seguido de otro que dejaron el espigado &#8216;Poatan&#8217; de espalda sobre la lona.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">WOOOOOW\ud83d\ude31 <a href=\"https:\/\/twitter.com\/stylebender?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@STYLEBENDER<\/a> LO NOQUEA EN EL SEGUNDO ROUND\u2757\ufe0f <a href=\"https:\/\/twitter.com\/hashtag\/UFC287?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#UFC287<\/a> <a href=\"https:\/\/t.co\/ir8TICeRK1\">pic.twitter.com\/ir8TICeRK1<\/a><\/p>\n<p>&mdash; UFC Espa\u00f1ol (@UFCEspanol) <a href=\"https:\/\/twitter.com\/UFCEspanol\/status\/1644926124626001920?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 9, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><strong>Con este nocaut, el primero de Adesanya desde su finalizaci\u00f3n sobre Robert Whittaker en 2019, el nigeriano recaptura el trono de la divisi\u00f3n y mejora su r\u00e9cord en la misma a 13 &#8211; 1<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">INCRE\u00cdBLE\ud83d\udc4f <a href=\"https:\/\/twitter.com\/stylebender?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@stylebender<\/a> recupera el t\u00edtulo de las 185 libras tras noquear a Alex Pereira\ud83c\udfc6 <a href=\"https:\/\/twitter.com\/hashtag\/UFC287?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#UFC287<\/a> <a href=\"https:\/\/t.co\/2gkeDWxHsz\">pic.twitter.com\/2gkeDWxHsz<\/a><\/p>\n<p>&mdash; UFC Espa\u00f1ol (@UFCEspanol) <a href=\"https:\/\/twitter.com\/UFCEspanol\/status\/1644927118185201664?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">April 9, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Pereira acumula su segunda derrota en las MMA, primera desde una sumisi\u00f3n en el tercer asalto durante lo que fue su debut en el deporte en 2015. El carioca se encontraba invicto sobre el oct\u00e1gono con un r\u00e9cord de 4 &#8211; 0.<\/p>","protected":false},"excerpt":{"rendered":"<p>El cintur\u00f3n de Peso Mediano de UFC regresa a las vitrinas de City Kickboxing. Israel Adesanya se sac\u00f3 la espina m\u00e1s grande de su carrera en la estelar del UFC 287 noqueando en dos asaltos a su verdugo m\u00e1s grande de los deportes de contacto: Alex Pereira. Adesanya, quien hab\u00eda quedado a segundos de finalizar [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":7277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,303],"tags":[330,329,381,538],"class_list":["post-7276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-ufc","tag-alex-pereira","tag-israel-adesanya","tag-resultados","tag-ufc-287"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/04\/Israel-Adesanya-3.webp?fit=1820%2C1213&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/7276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=7276"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/7276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/7277"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=7276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=7276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=7276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}