{"id":41331,"date":"2025-06-10T02:02:47","date_gmt":"2025-06-10T07:02:47","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=41331"},"modified":"2025-06-10T02:02:51","modified_gmt":"2025-06-10T07:02:51","slug":"merab-dvalishvili-sobrepasa-a-topuria-ranking","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/merab-dvalishvili-sobrepasa-a-topuria-ranking\/","title":{"rendered":"Merab Dvalishvili sobrepasa a Ilia Topuria en el ranking de libra por libra de UFC"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Un georgiano por otro en el top 3 del ranking m\u00e1s importante de <strong><a href=\"\/es\/tag\/ufc\/\">UFC<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"\/es\/tag\/merab-dvalishvili\/\">Merab Dvalishvili<\/a><\/strong> (20 &#8211; 4) extendi\u00f3 su reinado al mano de la divisi\u00f3n de 135 libras sometiendo en cosa de tres rounds a <strong>Sean O&#8217;Malley<\/strong> en el compromiso estelar del <strong>UFC 316<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.ufcespanol.com\/rankings\" target=\"_blank\" rel=\"noopener\">En la nueva actualizaci\u00f3n del ranking publicada la madrugada de este martes<\/a><\/strong>, Dvalishvili salt\u00f3 dos lugares, ubic\u00e1ndose ahora en la segunda casilla y sobrepasando a nada m\u00e1s y nada menos que <strong>Ilia Topuria<\/strong> y <strong>Jon Jones<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O&#8217;Malley qued\u00f3 fuera del top 15. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-41296\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-1.webp?w=1820&amp;ssl=1 1820w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Merab Dvalishvili sometiendo a Sean O&#8217;Malley en el UFC 316. Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para &#8216;The Machine&#8217;, la del s\u00e1bado fue su decimotercera victoria consecutiva y su segunda defensa de t\u00edtulo en lo que va de este 2025<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claro que si Topuria derrota a <strong>Charles Oliveira<\/strong> en el <strong>UFC 317<\/strong>, entonces \u00e9l tomar\u00e1 el lugar que ahora ocupa Dvalishvili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer escalaf\u00f3n lo tiene bien reservado <strong>Islam Makhachev<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Un georgiano por otro en el top 3 del ranking m\u00e1s importante de UFC. Merab Dvalishvili (20 &#8211; 4) extendi\u00f3 su reinado al mano de la divisi\u00f3n de 135 libras sometiendo en cosa de tres rounds a Sean O&#8217;Malley en el compromiso estelar del UFC 316. En la nueva actualizaci\u00f3n del ranking publicada la madrugada [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":41332,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,2580,299,300,303],"tags":[666,332,2933,654,434],"class_list":["post-41331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticia-destacada","category-noticias","category-noticias-de-mma","category-ufc","tag-ilia-topuria","tag-mma","tag-noticias-de-mma","tag-ranking","tag-ufc"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/06\/Merab-Dvalishvili-4.webp?fit=1720%2C1153&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/41331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=41331"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/41331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/41332"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=41331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=41331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=41331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}