{"id":41036,"date":"2025-05-29T18:13:27","date_gmt":"2025-05-29T23:13:27","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=41036"},"modified":"2025-05-29T18:13:32","modified_gmt":"2025-05-29T23:13:32","slug":"ilia-topuria-y-charles-oliveira-poster-ufc-317","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/ilia-topuria-y-charles-oliveira-poster-ufc-317\/","title":{"rendered":"Ilia Topuria y Charles Oliveira cubren el p\u00f3ster del UFC 317"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aunque firma su regreso a la divisi\u00f3n de Peso Liviano,<strong><a href=\"\/es\/tag\/ilia-topuria\/\"> Ilia Topuria<\/a><\/strong> est\u00e1 siendo promocionado por encima de <strong><a href=\"\/es\/tag\/charles-oliveira\/\">Charles Oliveira<\/a><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">UFC comparti\u00f3 esta tarde el p\u00f3ster oficial del <strong><a href=\"\/es\/tag\/ufc-317\/\">UFC 317<\/a><\/strong>, y llama la atenci\u00f3n que el nombre del espa\u00f1ol aparezca por encima que el de &#8216;Do Bronx&#8217;, n\u00famero dos del ranking. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/05\/UFC-317-Poster.webp?resize=819%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-41040\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/05\/UFC-317-Poster.webp?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/05\/UFC-317-Poster.webp?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/05\/UFC-317-Poster.webp?resize=768%2C960&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/05\/UFC-317-Poster.webp?resize=10%2C12&amp;ssl=1 10w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/05\/UFC-317-Poster.webp?w=960&amp;ssl=1 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><figcaption class=\"wp-element-caption\">P\u00f3ster del UFC 317. Zuffa, LLC. <\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Topuria renunci\u00f3 al cintur\u00f3n de Peso Pluma para regresar a 155 libras con la ilusi\u00f3n de alcanzar el estatus de campe\u00f3n doble. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El afiche tampoco se olvida del otro plato fuerte de la velada. <strong>Alexandre Pantoja<\/strong> realiza su cuarta defensa de cintur\u00f3n cuando se mida a <strong>Kai-Kara France<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El UFC 317 cierra el <em>International Fight Week<\/em> este 28 de junio desde la T-Mobile Arena en Las Vegas, Nevada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Aunque firma su regreso a la divisi\u00f3n de Peso Liviano, Ilia Topuria est\u00e1 siendo promocionado por encima de Charles Oliveira. UFC comparti\u00f3 esta tarde el p\u00f3ster oficial del UFC 317, y llama la atenci\u00f3n que el nombre del espa\u00f1ol aparezca por encima que el de &#8216;Do Bronx&#8217;, n\u00famero dos del ranking. Topuria renunci\u00f3 al cintur\u00f3n [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":40136,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,2580,299,300,303],"tags":[853,352,666,332,2933,2957,539,434,3057],"class_list":["post-41036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticia-destacada","category-noticias","category-noticias-de-mma","category-ufc","tag-alexandre-pantoja","tag-charles-oliveira","tag-ilia-topuria","tag-mma","tag-noticias-de-mma","tag-noticias-de-ufc","tag-poster","tag-ufc","tag-ufc-317"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/04\/Ilia-Topuria.webp?fit=1820%2C1213&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/41036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=41036"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/41036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/40136"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=41036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=41036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=41036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}