{"id":40822,"date":"2025-05-18T18:11:25","date_gmt":"2025-05-18T23:11:25","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=40822"},"modified":"2025-05-18T18:11:29","modified_gmt":"2025-05-18T23:11:29","slug":"veteranos-de-peso-welter-pelean-en-ufc-318","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/veteranos-de-peso-welter-pelean-en-ufc-318\/","title":{"rendered":"Veteranos del Peso Welter se miden en el UFC 318"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><a href=\"\/es\/tag\/neil-magny\/\">Neil Magny<\/a><\/strong> (29 &#8211; 13) y <strong><a href=\"\/es\/tag\/gunnar-nelson\/\">Gunnar Nelson<\/a><\/strong> (16 &#8211; 9 &#8211; 1) tendr\u00e1n la oportunidad de volver a la columna de la victoria este 19 de julio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"\/es\/tag\/ufc\/\">UFC<\/a><\/strong> anunci\u00f3 en redes sociales que los veteranos de Peso Welter se medir\u00e1n en las Preliminares del <strong><a href=\"\/es\/tag\/ufc-318\/\">UFC 318<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Magny, de 37 a\u00f1os, no compite desde un brutal KO a manos de <strong>Carlos Prates<\/strong> en la pelea estelar del <strong>UFC Vegas 100<\/strong>. El neoyorquino, 3 &#8211; 5 en sus \u00faltimas ocho disputas, cay\u00f3 tambi\u00e9n noqueado tres meses antes contra <strong>Michael Morales<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-39583\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Kevin-Holland.webp?w=1820&amp;ssl=1 1820w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Kevin Holland golpeando a Gunnar Nelson en el UFC Londres. Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nelson marc\u00f3 su regreso al oct\u00e1gono despu\u00e9s de dos a\u00f1os de ausencia con una derrota por decisi\u00f3n un\u00e1nime contra <strong>Kevin Holland<\/strong> en la cita coestelar del <strong>UFC Londres<\/strong> del pasado 22 de marzo. En 2022 y 2023 derrot\u00f3 a <strong>Takashi Sato<\/strong> y <strong>Bryan Barberena<\/strong>, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;Gunnie&#8217; es el peleador con m\u00e1s victorias por sometimiento en la historia de la divisi\u00f3n de 170 libras de UFC. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El UFC 318 se dar\u00e1 cita desde el Smoothie King Center de Nueva Orleans, Louisiana. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Neil Magny (29 &#8211; 13) y Gunnar Nelson (16 &#8211; 9 &#8211; 1) tendr\u00e1n la oportunidad de volver a la columna de la victoria este 19 de julio. UFC anunci\u00f3 en redes sociales que los veteranos de Peso Welter se medir\u00e1n en las Preliminares del UFC 318. Magny, de 37 a\u00f1os, no compite desde un [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":36002,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,300,303],"tags":[332,1267,2933,2957,434,3128],"class_list":["post-40822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-noticias-de-mma","category-ufc","tag-mma","tag-neil-magny","tag-noticias-de-mma","tag-noticias-de-ufc","tag-ufc","tag-ufc-318"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/10\/Neil-Magny.webp?fit=2400%2C1600&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/40822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=40822"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/40822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/36002"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=40822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=40822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=40822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}