{"id":40762,"date":"2025-05-16T11:14:11","date_gmt":"2025-05-16T16:14:11","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=40762"},"modified":"2025-05-16T11:14:21","modified_gmt":"2025-05-16T16:14:21","slug":"islam-makhachev-responde-a-ilia-topuria","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/islam-makhachev-responde-a-ilia-topuria\/","title":{"rendered":"Islam Makhachev responde a Topuria: &#8220;Solo eres un espa\u00f1ol boc\u00f3n con un buen peinado&#8221;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aun con sus miras en el cintur\u00f3n de Peso Welter, <strong><a href=\"\/es\/tag\/islam-makhachev\/\">Islam Makhachev<\/a><\/strong> no se olvida de <strong><a href=\"\/es\/tag\/ilia-topuria\/\">Ilia Topuria<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el daguestan\u00ed abandonando el Peso Liviano en b\u00fasqueda de un segundo cintur\u00f3n, Topuria, que har\u00e1 lo mismo cuando se mida a <strong>Charles<\/strong> <strong>Oliveira<\/strong> en el <strong>UFC 317<\/strong>, <strong><a href=\"https:\/\/www.mmaaldia.com\/es\/ilia-topuria-descarga-contra-islam-makhachev\/\" data-type=\"post\" data-id=\"40755\">tild\u00f3 de &#8216;hip\u00f3crita&#8217; al que en un futuro no muy lejano ser\u00e1 el excampe\u00f3n de la divisi\u00f3n<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Makhachev, naturalmente, no se qued\u00f3 callado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>La diferencia entre t\u00fa y yo es que yo limpie la cima de mi divisi\u00f3n y sub\u00ed. T\u00fa huiste de dos contendientes que ten\u00edan 5 (Diego Lopes) y 9 (Movsar Evloev) victorias consecutivas en la divisi\u00f3n de Peso Pluma<\/strong>&#8220;, respondi\u00f3 Makhachev en X. &#8220;<strong>Eres un donnadie en la divisi\u00f3n de Peso Liviano. Solo eres un espa\u00f1ol boc\u00f3n con un buen peinado. Anda consigue una victoria y luego podemos hablar, muchacho<\/strong>&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"embed-twitter\"><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Difference between me and you, that I cleaned top list in my division, moved to next, but you ran away from two contenders who had consecutive 5-9 wins in FW division. You are nobody in LW division, just a big mouth from Spain with nice haircut. Go get one W, and we can talk boy<\/p>&mdash; Makhachev Islam (@MAKHACHEVMMA) <a href=\"https:\/\/twitter.com\/MAKHACHEVMMA\/status\/1923008606527426901?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 15, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Makhachev se despide de 155 libras despu\u00e9s de alcanzar el r\u00e9cord de cuatro defensas titulares, dos de ellas ante el campe\u00f3n de Peso Pluma. Topuria cambia de aires con apenas una defensa: su espectacular KO en tres asaltos contra <strong>Max Holloway<\/strong> en Abu Dhabi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se espera que Makhachev desaf\u00ede a Jack Della Maddalena a fines de a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Aun con sus miras en el cintur\u00f3n de Peso Welter, Islam Makhachev no se olvida de Ilia Topuria. Con el daguestan\u00ed abandonando el Peso Liviano en b\u00fasqueda de un segundo cintur\u00f3n, Topuria, que har\u00e1 lo mismo cuando se mida a Charles Oliveira en el UFC 317, tild\u00f3 de &#8216;hip\u00f3crita&#8217; al que en un futuro no [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":32053,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,2580,299,300,303],"tags":[],"class_list":["post-40762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticia-destacada","category-noticias","category-noticias-de-mma","category-ufc"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/06\/Islam-Makhachev-2.webp?fit=1720%2C1236&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/40762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=40762"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/40762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/32053"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=40762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=40762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=40762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}