{"id":39988,"date":"2025-04-10T16:55:35","date_gmt":"2025-04-10T21:55:35","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=39988"},"modified":"2025-04-10T16:55:39","modified_gmt":"2025-04-10T21:55:39","slug":"fundador-de-gfl-habla-tras-eventos-cancelados","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/fundador-de-gfl-habla-tras-eventos-cancelados\/","title":{"rendered":"Fundador de GFL habla despu\u00e9s de la cancelaci\u00f3n de eventos: &#8220;Mi principal inversionista no cumpli\u00f3&#8221;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A un mes de los primeros eventos de su historia, <strong><a href=\"\/es\/tag\/gfl\/\">GFL<\/a><\/strong> todav\u00eda no contaba los recursos econ\u00f3micos para arrancar operaciones. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noche del mi\u00e9rcoles trascendi\u00f3 que la promoci\u00f3n cancel\u00f3 sus dos eventos programados para el 24 y 25 de mayo en el Shrine Auditorioum de Los \u00c1ngeles. Y de acuerdo a la respuesta de <strong>Darren Owen<\/strong>, presidente, la cosa no pinta tan bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Estoy trabajando en una soluci\u00f3n<\/strong>&#8220;, revel\u00f3 Owen por medio de mensaje de texto a Ariel Helwani (v\u00eda <strong><a href=\"https:\/\/sports.yahoo.com\/mma\/article\/gfl-founder-vows-to-keep-pushing-forward-after-event-cancellations-lays-out-companys-future-034401647.html\" target=\"_blank\" rel=\"noopener\">Uncrowned<\/a><\/strong>). &#8220;<strong>Mi principal inversionista no cumpli\u00f3 con su obligaci\u00f3n de abril, lo cual ha causado un problema. Te mantendr\u00e9 actualizado pero creo que lo solucionaremos. Creo que podremos hacerlo en junio. Adicionalmente preveo que el evento no tendr\u00e1 lugar en California, pero seguiremos hacia adelante. Creo que tendremos que postergar las fechas para el 15 y 16 de junio. Lo confirmar\u00e9 lo antes posible. Ha sido una semana frustrante pero creo que ya existe una soluci\u00f3n<\/strong>&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En meses pasados, GFL firm\u00f3 a un gran n\u00famero de peleadores con pasado en <strong>UFC<\/strong>, <strong>Bellator<\/strong> y <strong>PFL<\/strong>. Ahora habr\u00e1 que ver si se cumple con la nueva fecha prevista. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A un mes de los primeros eventos de su historia, GFL todav\u00eda no contaba los recursos econ\u00f3micos para arrancar operaciones. La noche del mi\u00e9rcoles trascendi\u00f3 que la promoci\u00f3n cancel\u00f3 sus dos eventos programados para el 24 y 25 de mayo en el Shrine Auditorioum de Los \u00c1ngeles. Y de acuerdo a la respuesta de Darren [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":38751,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,300,303],"tags":[3007,3005,332,2933],"class_list":["post-39988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-noticias-de-mma","category-ufc","tag-darren-owen","tag-gfl","tag-mma","tag-noticias-de-mma"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Urijah-Faber.webp?fit=1200%2C800&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=39988"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/38751"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=39988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=39988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=39988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}