{"id":39887,"date":"2025-04-04T17:51:50","date_gmt":"2025-04-04T22:51:50","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=39887"},"modified":"2025-04-04T17:51:53","modified_gmt":"2025-04-04T22:51:53","slug":"todo-lo-que-necesitas-saber-del-ufc-vegas-105","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/todo-lo-que-necesitas-saber-del-ufc-vegas-105\/","title":{"rendered":"Todo lo que necesitas saber antes del UFC Vegas 105"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><a href=\"\/es\/tag\/josh-emmett\/\">Josh Emmett<\/a><\/strong> buscar\u00e1 aferrarse con u\u00f1as y dientes al top 10 de Peso Pluma cuando reciba al invicto <strong><a href=\"\/es\/tag\/lerone-murphy\/\">Lerone Murphy<\/a><\/strong> en el evento central del <strong><a href=\"\/es\/tag\/ufc-vegas-105\/\">UFC Vegas 105<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n echamos un vistazo a los datos m\u00e1s llamativos de la cartelera. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Josh Emmett<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Disputar\u00e1 su cuarta pelea estelar en UFC<\/li>\n\n\n\n<li>Sostiene un r\u00e9cord de 1 &#8211; 2 en peleas estelares de UFC<\/li>\n\n\n\n<li><strong>Con 40 a\u00f1os es el peleador m\u00e1s viejo de la cartelera<\/strong><\/li>\n\n\n\n<li><strong>Posee el r\u00e9cord por m\u00e1s <em>knockdowns<\/em> (12) en la historia del Peso Pluma<\/strong><\/li>\n\n\n\n<li>Comparte el r\u00e9cord por m\u00e1s <em>knockdowns<\/em> en peleas consecutivas (7)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Lerone Murphy<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Est\u00e1 invicto en UFC con un r\u00e9cord de 7 &#8211; 0 &#8211; 1<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Brad Tavares<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Compite para UFC desde 2010<\/li>\n\n\n\n<li><strong>Es el segundo peleador con m\u00e1s victorias (15) en la historia del Peso Mediano <\/strong><\/li>\n\n\n\n<li>Es el peleador con m\u00e1s victorias por decisi\u00f3n (13) en la historia del Peso Mediano<\/li>\n\n\n\n<li>Comparte el r\u00e9cord por m\u00e1s victorias por decisi\u00f3n dividida (3) en la historia del Peso Mediano<\/li>\n\n\n\n<li><strong>Es el peleador con m\u00e1s peleas (25) en la historia del Peso Mediano<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gerald Meerschaert<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Posee el r\u00e9cord por m\u00e1s victorias por sumisi\u00f3n (11) en la historia del Peso Mediano<\/strong><\/li>\n\n\n\n<li>Once de sus doce victorias por finalizaci\u00f3n en UFC han sido por sometimiento<\/li>\n\n\n\n<li>Posee un \u00edndice de finalizaci\u00f3n en UFC de 100%<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dione Barbosa<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Es la favorita m\u00e1s grande de la velada con un -1000<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Loma Lookboonmee<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Es la segunda favorita m\u00e1s grande de la velada con -900<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vanessa Demopoulos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Es la campeona inaugural de Peso Paja de LFA<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El UFC Vegas 105 se realizar\u00e1 desde el UFC Apex.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Josh Emmett buscar\u00e1 aferrarse con u\u00f1as y dientes al top 10 de Peso Pluma cuando reciba al invicto Lerone Murphy en el evento central del UFC Vegas 105. A continuaci\u00f3n echamos un vistazo a los datos m\u00e1s llamativos de la cartelera. Josh Emmett Lerone Murphy Brad Tavares Gerald Meerschaert Dione Barbosa Loma Lookboonmee Vanessa Demopoulos [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":39890,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,2580,299,300,303],"tags":[332,2933,2957,434,3022],"class_list":["post-39887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticia-destacada","category-noticias","category-noticias-de-mma","category-ufc","tag-mma","tag-noticias-de-mma","tag-noticias-de-ufc","tag-ufc","tag-ufc-vegas-105"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/04\/UFC-Vegas-105.webp?fit=1280%2C720&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=39887"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/39890"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=39887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=39887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=39887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}