{"id":39384,"date":"2025-03-13T12:16:28","date_gmt":"2025-03-13T17:16:28","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=39384"},"modified":"2025-03-13T12:16:35","modified_gmt":"2025-03-13T17:16:35","slug":"belal-muhammad-no-derribara-en-el-ufc-315","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/belal-muhammad-no-derribara-en-el-ufc-315\/","title":{"rendered":"Belal Muhammad asegura que no derribar\u00e1 a Jack Della Maddalena en el UFC 315"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Pese a ser uno de los diez peleadores con m\u00e1s derribos (43) en la historia de la divisi\u00f3n de Peso Welter de <strong><a href=\"\/es\/tag\/ufc\/\">UFC<\/a><\/strong>, <strong><a href=\"\/es\/tag\/belal-muhammad\/\">Belal Muhammad<\/a><\/strong>, vigente campe\u00f3n de la categor\u00eda, solo planea usar sus manos en la estelar del <strong><a href=\"\/es\/tag\/ufc-315\/\">UFC 315<\/a><\/strong> cuando mida fuerzas con el retador <strong><a href=\"\/es\/tag\/jack-della-maddalena\/\">Jack Della Maddalena<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Voy a entrar a la jaula y le voy a ganar en el boxeo<\/strong>&#8220;, asegur\u00f3 Muhammad en una reciente aparici\u00f3n en un podcast (v\u00eda <strong><a href=\"https:\/\/www.mmamania.com\/2025\/3\/13\/24384847\/belal-canelo-hands-muhammad-vows-outbox-jack-della-maddalena-ufc-315-im-not-gonna-shoot-one-takedown\" target=\"_blank\" rel=\"noopener\">MMA Mania<\/a><\/strong>). &#8220;<strong>No voy a intentar ni un solo derribo. Le voy a ense\u00f1ar el significado de tener las manos de Canelo<\/strong>&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/03\/Jack-Della-Maddalena-1.webp?resize=1024%2C683&#038;ssl=1\" alt=\"\" class=\"wp-image-28696\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/03\/Jack-Della-Maddalena-1.webp?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/03\/Jack-Della-Maddalena-1.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/03\/Jack-Della-Maddalena-1.webp?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/03\/Jack-Della-Maddalena-1.webp?resize=1536%2C1025&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/03\/Jack-Della-Maddalena-1.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/03\/Jack-Della-Maddalena-1.webp?w=2048&amp;ssl=1 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Jack Della Maddalena golpeando a Gilbert Burns en el UFC 299. Cr\u00e9dito: Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima vez que Muhammad no pretendi\u00f3 llevar la pelea a la lona fue durante su combate con <strong>Gilbert Burns<\/strong> en la coestelar del <strong>UFC 288<\/strong>. Lo que s\u00ed hizo fue conectar 123 golpes para llevarse la victoria por decisi\u00f3n un\u00e1nime. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El peleador palestino retom\u00f3 su plan de juego para su revancha con <strong>Leon Edwards<\/strong> en el <strong>UFC 304<\/strong>, logrando nueve de trece derribos para capturar el cintur\u00f3n de 170 libras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El UFC 315 se celebra el 10 de mayo desde el Bell Center en Quebec, Montreal, Canad\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Pese a ser uno de los diez peleadores con m\u00e1s derribos (43) en la historia de la divisi\u00f3n de Peso Welter de UFC, Belal Muhammad, vigente campe\u00f3n de la categor\u00eda, solo planea usar sus manos en la estelar del UFC 315 cuando mida fuerzas con el retador Jack Della Maddalena. &#8220;Voy a entrar a la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":39387,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,300,303],"tags":[],"class_list":["post-39384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-noticias-de-mma","category-ufc"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Belal-Muhammad-1.webp?fit=1200%2C800&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=39384"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/39387"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=39384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=39384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=39384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}