{"id":39370,"date":"2025-03-12T10:10:05","date_gmt":"2025-03-12T15:10:05","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=39370"},"modified":"2025-03-12T10:10:10","modified_gmt":"2025-03-12T15:10:10","slug":"rafael-fiziev-analiza-bajar-a-145-libras","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/rafael-fiziev-analiza-bajar-a-145-libras\/","title":{"rendered":"Rafael Fiziev analiza bajar al Peso Pluma"},"content":{"rendered":"<p class=\"wp-block-paragraph\">0 &#8211; 3 en sus \u00faltimas incursiones sobre el oct\u00e1gono, <strong><a href=\"\/es\/tag\/rafael-fiziev\/\">Rafael Fiziev<\/a><\/strong> est\u00e1 contemplando realizar un cambio dr\u00e1stico en su carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fiziev, que viene de caer por decisi\u00f3n un\u00e1nime ante <strong>Justin Gaethje<\/strong> en la coestelar del <strong><a href=\"\/es\/tag\/ufc-313\/\">UFC 313<\/a><\/strong>, no ve con malos ojos bajar a 145 libras. As\u00ed lo explic\u00f3 durante una entrevista con Ariel Helwani.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Estoy comenzando a pensar sobre cambiar de divisi\u00f3n<\/strong>&#8220;, explic\u00f3 (v\u00eda <strong><a href=\"http:\/\/\u00a1Recuerden seguir a MMA al D\u00eda en X!\">MMA Mania<\/a><\/strong>). &#8220;<strong>Esta vez cort\u00e9 peso muy f\u00e1cil y y fue en corto aviso. Fue muy f\u00e1cil, hermano. Toda la semana mi nutricionista trat\u00f3 de hacerme ganar peso porque lo estaba perdiendo muy r\u00e1pido. As\u00ed que s\u00ed, tengo que pensarlo. Es posible<\/strong>&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Justin-Gaethje-2.webp?resize=1024%2C684&#038;ssl=1\" alt=\"\" class=\"wp-image-39320\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Justin-Gaethje-2.webp?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Justin-Gaethje-2.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Justin-Gaethje-2.webp?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Justin-Gaethje-2.webp?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Justin-Gaethje-2.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/03\/Justin-Gaethje-2.webp?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Justin Gaethje golpeando a Rafael Fiziev en el UFC 313. PXImages. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de su derrota del s\u00e1bado, Fiziev, decimoprimero del ranking de 155 libras, ya hab\u00eda sufrido derrotas en 2023 a manos de <strong>Mateusz<\/strong> <strong>Gamrot<\/strong> y el propio Gaethje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El kirguistan\u00ed no gana desde un KO sobre el excampe\u00f3n <strong>Rafael Dos Anjos<\/strong> en julio de 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>0 &#8211; 3 en sus \u00faltimas incursiones sobre el oct\u00e1gono, Rafael Fiziev est\u00e1 contemplando realizar un cambio dr\u00e1stico en su carrera. Fiziev, que viene de caer por decisi\u00f3n un\u00e1nime ante Justin Gaethje en la coestelar del UFC 313, no ve con malos ojos bajar a 145 libras. As\u00ed lo explic\u00f3 durante una entrevista con Ariel [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":14936,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,300,303],"tags":[332,2957,3087],"class_list":["post-39370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-noticias-de-mma","category-ufc","tag-mma","tag-noticias-de-ufc","tag-rafael-fizie"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/07\/Rafael-Fiziev.webp?fit=1820%2C1213&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=39370"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/14936"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=39370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=39370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=39370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}