{"id":39343,"date":"2025-03-10T11:32:39","date_gmt":"2025-03-10T16:32:39","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=39343"},"modified":"2025-03-10T11:32:42","modified_gmt":"2025-03-10T16:32:42","slug":"jalin-turner-se-retira-de-las-mma","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/jalin-turner-se-retira-de-las-mma\/","title":{"rendered":"Jalin Turner se retira de las MMA"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><a href=\"\/es\/tag\/jalin-turner\/\">Jalin Turner<\/a><\/strong> ha decidido retirarse de las MMA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Peso Liviano de 29 a\u00f1os sufri\u00f3 una tercera derrota consecutiva al ser sometido en un asalto por el chileno <strong>Ignacio Bahamondes<\/strong> durante el <em>Main Card<\/em> del <strong>UFC 313<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante una entrevista con Sportsnet, Turner explic\u00f3 en qu\u00e9 basa su decisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Ya hab\u00eda entretenido la idea de retirarme despu\u00e9s del UFC 300<\/strong>&#8220;, explic\u00f3 (v\u00eda <strong><a href=\"https:\/\/mmajunkie.usatoday.com\/2025\/03\/ufc-313-jalin-turner-emotional-retirement-decision-loss-vs-bahamondes\" target=\"_blank\" rel=\"noopener\">MMA Junkie<\/a><\/strong>). &#8220;<strong>Me tom\u00e9 algo de tiempo fuera, sabes. Segu\u00ed entrenando, tratando de enfocarme en mi salud mental. Es duro, hombre. Pelear es duro. Lo llevo haciendo 12 a\u00f1os y, o tienes que estar 100% comprometido o no lo vas a lograr. Estando en la jaula no estuve tan enfocado como pens\u00e9 que iba a estar. La decisi\u00f3n la tom\u00e9 bas\u00e1ndome en esta pelea. Sent\u00eda que iba a ganar. Lo he visto pelear. Es un prospecto. Se merec\u00eda la oportunidad y sent\u00ed que me levantar\u00edan la mano, pero no ocurri\u00f3. Es emocional, pero lo llevo pensando por los \u00faltimos once meses. Dud\u00e9 firmar el contrato porque no sab\u00eda si me iba a retirar<\/strong>, <strong>no sab\u00eda por cu\u00e1nto m\u00e1s quer\u00eda hacer esto. Mis hijos est\u00e1n envejeciendo. No quiero seguir recibiendo da\u00f1o. La vida me ha dado algunos golpes en los \u00faltimos once meses. As\u00ed que necesito alejarme por un rato, tal vez para siempre<\/strong>&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/12\/Jalin-Turner-2.webp?resize=1024%2C683&#038;ssl=1\" alt=\"\" class=\"wp-image-24658\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/12\/Jalin-Turner-2.webp?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/12\/Jalin-Turner-2.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/12\/Jalin-Turner-2.webp?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/12\/Jalin-Turner-2.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/12\/Jalin-Turner-2.webp?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Jalin Turner golpeando a Bobby Green en el UFC Austin. Cr\u00e9dito: Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Turner, a esta hora decimotercero del ranking de 155 libras, lleg\u00f3 a <strong><a href=\"\/es\/tag\/ufc\/\">UFC<\/a><\/strong> en 2018 proveniente del <strong><em>Dana White&#8217;s Contender Series<\/em><\/strong>. Entre 2020 y 2022 lleg\u00f3 a apilar una racha de cinco victorias en fila por sumisi\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;The Tarantula&#8217; se aleja de las MMA con un r\u00e9cord de 14 &#8211; 9 (7 &#8211; 6 sobre el oct\u00e1gono).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Jalin Turner ha decidido retirarse de las MMA. El Peso Liviano de 29 a\u00f1os sufri\u00f3 una tercera derrota consecutiva al ser sometido en un asalto por el chileno Ignacio Bahamondes durante el Main Card del UFC 313. Durante una entrevista con Sportsnet, Turner explic\u00f3 en qu\u00e9 basa su decisi\u00f3n. &#8220;Ya hab\u00eda entretenido la idea de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,300,303],"tags":[332,2933,2957,572,434],"class_list":["post-39343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-noticias-de-mma","category-ufc","tag-mma","tag-noticias-de-mma","tag-noticias-de-ufc","tag-retiro","tag-ufc"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/11\/Jalin-Turner.webp?fit=2560%2C1867&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=39343"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/24164"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=39343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=39343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=39343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}