{"id":39006,"date":"2025-02-25T15:29:32","date_gmt":"2025-02-25T20:29:32","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=39006"},"modified":"2025-02-25T15:29:35","modified_gmt":"2025-02-25T20:29:35","slug":"anthony-hernandez-ingresa-al-top-10-de-185-libras","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/anthony-hernandez-ingresa-al-top-10-de-185-libras\/","title":{"rendered":"Anthony Hernandez ingresa al top 10 de Peso Mediano"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><a href=\"\/es\/tag\/anthony-hernandez\/\">Anthony Hernandez<\/a><\/strong> fue uno de los ganadores m\u00e1s grandes del <strong>UFC Seattle<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la pelea coestelar de la velada, el californiano apil\u00f3 una s\u00e9ptima victoria consecutiva al imponerse por decisi\u00f3n un\u00e1nime a <strong><a href=\"\/es\/tag\/brendan-allen\/\">Brendan Allen<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hernandez, que ya hab\u00eda derrotado al excampe\u00f3n de <strong>LFA<\/strong> en 2018, <strong><a href=\"https:\/\/www.ufcespanol.com\/rankings\" target=\"_blank\" rel=\"noopener\">subi\u00f3 tres lugares en la m\u00e1s reciente actualizaci\u00f3n del ranking<\/a><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;Fluffy&#8217;, 8 &#8211; 2 sobre el oct\u00e1gono, ahora se posiciona en la novena casilla.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-38951\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez.webp?w=1820&amp;ssl=1 1820w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Anthony Hernandez encajando una matale\u00f3n contra Brendan Allen en el UFC Seattle. Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Allen desciende al d\u00e9cimo escalaf\u00f3n. El peleador de 28 a\u00f1os ven\u00eda de caer en las tarjetas ante <strong>Nassourdine Imavov<\/strong>, actual n\u00famero uno del ranking, en el <strong>UFC Par\u00eds<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Anthony Hernandez fue uno de los ganadores m\u00e1s grandes del UFC Seattle. En la pelea coestelar de la velada, el californiano apil\u00f3 una s\u00e9ptima victoria consecutiva al imponerse por decisi\u00f3n un\u00e1nime a Brendan Allen. Hernandez, que ya hab\u00eda derrotado al excampe\u00f3n de LFA en 2018, subi\u00f3 tres lugares en la m\u00e1s reciente actualizaci\u00f3n del ranking. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":39008,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,300,303],"tags":[2633,654],"class_list":["post-39006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-noticias-de-mma","category-ufc","tag-anthony-hernandez-2","tag-ranking"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Anthony-Hernandez-1.webp?fit=1720%2C1147&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=39006"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/39006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/39008"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=39006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=39006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=39006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}