{"id":38778,"date":"2025-02-19T11:36:36","date_gmt":"2025-02-19T16:36:36","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=38778"},"modified":"2025-02-19T11:36:41","modified_gmt":"2025-02-19T16:36:41","slug":"gregory-rodrigues-derrota-en-el-ufc-vegas-102","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/gregory-rodrigues-derrota-en-el-ufc-vegas-102\/","title":{"rendered":"Gregory Rodrigues culpa al corte de peso por su derrota en el UFC Vegas 102: &#8220;Mi cuerpo no estaba respondiendo&#8221;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Si <strong><a href=\"\/es\/tag\/gregory-rodrigues\/\">Gregory Rodrigues<\/a><\/strong> luc\u00eda enorme en la estelar del <strong><a href=\"\/es\/tag\/ufc-vegas-102\/\">UFC Vegas 102<\/a><\/strong> es porque el peleador definitivamente es demasiado grande para el Peso Mediano. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El brasile\u00f1o se perdi\u00f3 la oportunidad de ingresar al top 10 de la divisi\u00f3n al sucumbir por un nocaut t\u00e9cnico en el cuarto round a manos del fogueado <strong>Jared Cannonier<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos d\u00edas despu\u00e9s del combate, Rodrigues detall\u00f3 complicaciones durante el corte de peso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>La mayor\u00eda de personas desconocen esto, pero tuve serios problemas para recuperarme del corte de peso<\/strong>&#8220;, asegur\u00f3 &#8216;Robocop&#8217; en redes sociales (v\u00eda <strong><a href=\"https:\/\/www.mmafighting.com\/2025\/2\/18\/24367782\/my-body-just-wasnt-responding-gregory-rodrigues-reveals-serious-issues-jared-cannonier-loss-ufc\" target=\"_blank\" rel=\"noopener\">MMA Fighting<\/a><\/strong>). &#8220;<strong>Mi cuerpo no estaba respondiendo. Me sigo preguntando c\u00f3mo se hubiesen dado las cosas de haber estado al 100%. Pero basta de historias tristes. \u00a1Robocop nuca muere! Hora de recargar, resetear el sistema y mejorar, \u00a1porque apenas estoy comenzando<\/strong>&#8220;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?resize=1024%2C682&#038;ssl=1\" alt=\"\" class=\"wp-image-38712\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier-1.webp?w=1820&amp;ssl=1 1820w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Jared Cannonier golpeando a Gregory Rodrigues en el UFC Vegas 102. Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Rodrigues, excampe\u00f3n de <strong>LFA<\/strong>, jam\u00e1s ha tenido problemas sobre la b\u00e1scula para las diez peleas que ha disputado en <strong><a href=\"\/es\/tag\/ufc\/\">UFC<\/a><\/strong> hasta la fecha. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El talento de <strong>Kill Cliff FC<\/strong> lleg\u00f3 al evento en una racha de tres victorias consecutivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Si Gregory Rodrigues luc\u00eda enorme en la estelar del UFC Vegas 102 es porque el peleador definitivamente es demasiado grande para el Peso Mediano. El brasile\u00f1o se perdi\u00f3 la oportunidad de ingresar al top 10 de la divisi\u00f3n al sucumbir por un nocaut t\u00e9cnico en el cuarto round a manos del fogueado Jared Cannonier. Dos [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":38709,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,2580,299,300,303],"tags":[332,2957,434,2997],"class_list":["post-38778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticia-destacada","category-noticias","category-noticias-de-mma","category-ufc","tag-mma","tag-noticias-de-ufc","tag-ufc","tag-ufc-vegas-102"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/Jared-Cannonier.webp?fit=1820%2C1213&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/38778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=38778"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/38778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/38709"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=38778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=38778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=38778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}