{"id":38731,"date":"2025-02-17T15:08:36","date_gmt":"2025-02-17T20:08:36","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=38731"},"modified":"2025-02-17T15:08:40","modified_gmt":"2025-02-17T20:08:40","slug":"cartelera-completa-para-el-one-171","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/cartelera-completa-para-el-one-171\/","title":{"rendered":"Cartelera completa para el ONE 171 de este jueves"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Catorce combates en cuatro disciplinas marcan el regreso de <strong><a href=\"\/es\/tag\/one-championship\/\">ONE Championship<\/a><\/strong> a Catar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong><a href=\"\/es\/tag\/one-171\/\">ONE 171<\/a><\/strong> ser\u00e1 encabezado por una pelea de trilog\u00eda entre <strong>Joshua Pacio<\/strong>, monarca de Peso Paja, y el excampe\u00f3n <strong>Jarred Brooks<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ex-<strong>UFC<\/strong> emparej\u00f3 el marcador tras ser descalificado por azotar al filipino durante su combate coestelar en <strong>ONE 166<\/strong> celebrado en marzo de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la coestelar, <strong>Jonathan Haggerty<\/strong> expone su corona de Peso Gallo de Kickboxing ante el chino<strong> Wei Rui<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Roberto Soldic<\/strong>, <strong>Aung La Nsang<\/strong> y <strong>Bibiano Fernandes<\/strong> son otros de los nombres destacos que ver\u00e1n acci\u00f3n en la cartele<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Main Card<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Joshua Pacio (c) vs. Jarred Brooks &#8211; Cintur\u00f3n Mundial de Peso Paja<\/li>\n\n\n\n<li>Jonathan Haggerty (c) vs. Wei Rui &#8211; Cintur\u00f3n Mundial de Peso Gallo de Kickboxing<\/li>\n\n\n\n<li><strong>Dagi Arslanaliev<\/strong> vs. Roberto Soldic<\/li>\n\n\n\n<li><strong>Ilias Ennahachi<\/strong> vs. <strong>Petchtanong Petchfergus<\/strong> &#8211; Kickboxing<\/li>\n\n\n\n<li><strong>Shamil Edrogan<\/strong> vs. Aung La Nsang<\/li>\n\n\n\n<li><strong>Shamil Gasanov<\/strong> vs. <strong>Martin Nguyen<\/strong><\/li>\n\n\n\n<li>Bibiano Fernandes vs. <strong>Kevin Belingon<\/strong><\/li>\n\n\n\n<li><strong>Mauro Cerilli<\/strong> vs. <strong>Kirill Grishenko<\/strong><\/li>\n\n\n\n<li><strong>Jake Peacock<\/strong> vs. <strong>Shinji Suzuki<\/strong> &#8211; Muay Thai<\/li>\n\n\n\n<li><strong>Ayaka Miura<\/strong> vs. <strong>Ritu Phogat<\/strong><\/li>\n\n\n\n<li><strong>Kade Ruotolo<\/strong> vs. <strong>Nicolas Vigna<\/strong> <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Lead Card<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Zayed Alkatheeri<\/strong> vs. <strong>Jarrah Al Hazza<\/strong> &#8211; Submission Grappling<\/li>\n\n\n\n<li><strong>Abdullo Khodzhaev<\/strong> vs. <strong>Wilian Poles<\/strong><\/li>\n\n\n\n<li><strong>Hussein Salem<\/strong> vs. <strong>Walter Cogliandro<\/strong> <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El ONE 171 se celebra desde la Lusail Sports Arena en Lusail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Catorce combates en cuatro disciplinas marcan el regreso de ONE Championship a Catar. El ONE 171 ser\u00e1 encabezado por una pelea de trilog\u00eda entre Joshua Pacio, monarca de Peso Paja, y el excampe\u00f3n Jarred Brooks. El ex-UFC emparej\u00f3 el marcador tras ser descalificado por azotar al filipino durante su combate coestelar en ONE 166 celebrado [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":38733,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,1884,299,349],"tags":[360,1294,559],"class_list":["post-38731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-muay-thai","category-noticias","category-one-championship","tag-main-card","tag-one","tag-one-championship"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2025\/02\/250220-DOH-ONE171-1800x1200px.webp?fit=1800%2C1200&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/38731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=38731"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/38731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/38733"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=38731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=38731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=38731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}