{"id":37643,"date":"2024-12-19T01:49:33","date_gmt":"2024-12-19T06:49:33","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=37643"},"modified":"2024-12-19T01:49:37","modified_gmt":"2024-12-19T06:49:37","slug":"alex-pereira-descarta-a-ankalaev-como-retador","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/alex-pereira-descarta-a-ankalaev-como-retador\/","title":{"rendered":"Alex Pereira descarta a Magomed Ankalaev como su pr\u00f3ximo retador"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Se desconoce cu\u00e1ndo <strong><a href=\"\/es\/tag\/alex-pereira\/\">Alex Pereira<\/a><\/strong> volver\u00e1 al oct\u00e1gono en 2025, pero no ser\u00e1 contra <strong><a href=\"\/es\/tag\/magomed-ankalaev\/\">Magomed Ankalaev<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A manera de burla, el campe\u00f3n reinante de los Pesos Completos descart\u00f3 al daguestan\u00ed como su pr\u00f3ximo retador al trono. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>\u00a1No ser\u00e1 Ankalaev!<\/strong>&#8220;, escribi\u00f3 &#8216;Poatan&#8217; con emotic\u00f3n de llanto inclu\u00eddo en un publicaci\u00f3n de <strong><a href=\"https:\/\/x.com\/AlexPereiraUFC\/status\/1869561034601898338\">X<\/a><\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">It won\u2019t be Ankalaev ! \ud83d\ude2d<\/p>&mdash; Alex &quot;Poatan&quot; Pereira (@AlexPereiraUFC) <a href=\"https:\/\/twitter.com\/AlexPereiraUFC\/status\/1869561034601898338?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 19, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ankalaev se habr\u00eda ganado una oportunidad titular despu\u00e9s de imponerse por decisi\u00f3n un\u00e1nime a <strong>Aleksandar Raki\u0107<\/strong> en el <em>Main Card<\/em> del <strong>UFC<\/strong> <strong>308<\/strong>. El ruso cursa una racha invicta de 11 &#8211; 0 &#8211; 1 &#8211; (1 NC) en sus \u00faltimas trece peleas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pereira, por su parte, viene de efectuar su segunda defensa de cintur\u00f3n con un TKO en el cuarto asalto sobre <strong>Khalil Rountree Jr.<\/strong> en el <strong>UFC 307<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Se desconoce cu\u00e1ndo Alex Pereira volver\u00e1 al oct\u00e1gono en 2025, pero no ser\u00e1 contra Magomed Ankalaev. A manera de burla, el campe\u00f3n reinante de los Pesos Completos descart\u00f3 al daguestan\u00ed como su pr\u00f3ximo retador al trono. &#8220;\u00a1No ser\u00e1 Ankalaev!&#8220;, escribi\u00f3 &#8216;Poatan&#8217; con emotic\u00f3n de llanto inclu\u00eddo en un publicaci\u00f3n de X. Ankalaev se habr\u00eda ganado [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":35903,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,2580,299,300,303],"tags":[330,2933,2957],"class_list":["post-37643","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticia-destacada","category-noticias","category-noticias-de-mma","category-ufc","tag-alex-pereira","tag-noticias-de-mma","tag-noticias-de-ufc"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/10\/Alex-Pereira-3.webp?fit=1820%2C1213&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/37643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=37643"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/37643\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/35903"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=37643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=37643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=37643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}