{"id":33854,"date":"2024-07-31T02:18:31","date_gmt":"2024-07-31T07:18:31","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=33854"},"modified":"2024-07-31T02:18:37","modified_gmt":"2024-07-31T07:18:37","slug":"precio-de-entrada-mas-barata-de-noche-ufc","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/precio-de-entrada-mas-barata-de-noche-ufc\/","title":{"rendered":"La entrada m\u00e1s barata para Noche UFC est\u00e1 fijada en $3,000 d\u00f3lares"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Presenciar el primer &#8211; y \u00fanico &#8211; evento de <strong><a href=\"\/es\/tag\/ufc\/\">UFC<\/a><\/strong> desde la Sphere de Las Vegas costar\u00e1 bastante pasta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La venta de boletos de la segunda edici\u00f3n de <a href=\"\/es\/tag\/noche-ufc\/\">Noche UFC<\/a>, aka <a href=\"\/es\/tag\/ufc-306\/\">UFC 306<\/a>, salieron a la venta el lunes y, seg\u00fan los valores en Ticketmaster, los ingresos van desde los $3,000 hasta los $12,000 d\u00f3lares<\/strong>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/06\/Noche-UFC.webp?resize=1024%2C576&#038;ssl=1\" alt=\"\" class=\"wp-image-32855\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/06\/Noche-UFC.webp?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/06\/Noche-UFC.webp?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/06\/Noche-UFC.webp?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/06\/Noche-UFC.webp?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/06\/Noche-UFC.webp?w=1152&amp;ssl=1 1152w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Noche UFC. Cr\u00e9dito: Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dana White planea arrojar la casa por la ventana aprovechando el dise\u00f1o arquitect\u00f3nico del novedoso recinto. <strong>El CEO de UFC afirma haber invertido $17 millones de d\u00f3lares en los preparativos para el evento<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.mmaaldia.com\/es\/omalley-vs-dvalishvili-oficial-para-noche-ufc\/\" data-type=\"post\" data-id=\"33808\">Noche UFC ser\u00e1 encabezo por una pelea titular entre Sean O&#8217;Malley, campe\u00f3 de Peso Gallo, y Merab Dvalishvili<\/a><\/strong>. <strong><a href=\"https:\/\/www.mmaaldia.com\/es\/grasso-vs-shevchenko-3-oficial-para-noche-ufc\/\" data-type=\"post\" data-id=\"33812\">La trilog\u00eda entre Alexa Grasso y Valentina Shevchenko ser\u00e1 el otro plato fuerte de la velada<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento se celebra este 14 de septiembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>","protected":false},"excerpt":{"rendered":"<p>Presenciar el primer &#8211; y \u00fanico &#8211; evento de UFC desde la Sphere de Las Vegas costar\u00e1 bastante pasta. La venta de boletos de la segunda edici\u00f3n de Noche UFC, aka UFC 306, salieron a la venta el lunes y, seg\u00fan los valores en Ticketmaster, los ingresos van desde los $3,000 hasta los $12,000 d\u00f3lares. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":33855,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,2580,299,300,303],"tags":[1928,434,2457],"class_list":["post-33854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticia-destacada","category-noticias","category-noticias-de-mma","category-ufc","tag-noche-ufc","tag-ufc","tag-ufc-306"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/07\/Alexa-Grasso.webp?fit=2400%2C1600&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/33854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=33854"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/33854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/33855"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=33854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=33854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=33854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}