{"id":33084,"date":"2024-07-03T06:29:25","date_gmt":"2024-07-02T19:59:25","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=33084"},"modified":"2024-07-03T06:29:29","modified_gmt":"2024-07-02T19:59:29","slug":"ufc-nombra-los-mejores-debuts-de-2024","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/ufc-nombra-los-mejores-debuts-de-2024\/","title":{"rendered":"UFC nombra los 5 mejores debuts de la primera mitad de 2024"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Con la primera mitad de 2024 ya siendo cosa del pasado, <strong><a href=\"\/es\/tag\/ufc\/\">UFC<\/a><\/strong> ha hecho una retrospectiva sobre los mejores debuts que tuvieron lugar sobre el oct\u00e1gono entre enero y junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.ufcespanol.com\/news\/newcomers-2024-half-year-awards\" target=\"_blank\" rel=\"noopener\">De los cinco atletas que fueron seleccionados<\/a><\/strong>, la organizaci\u00f3n estima que la judoca ol\u00edmpica <strong><a href=\"\/es\/tag\/kayla-harrison\/\">Kayla Harrison<\/a><\/strong> tuvo el debut m\u00e1s impresionante de todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La veterana de <strong>PFL<\/strong> debut\u00f3 en el Peso Gallo y arras\u00f3 con la excampeona <strong>Holly Holm<\/strong> hasta someterla en el segundo asalto durante las Preliminares del hist\u00f3rico <strong>UFC 300<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/04\/Kayla-Harrison-1-1.webp?resize=1024%2C683&#038;ssl=1\" alt=\"\" class=\"wp-image-30396\" title=\"\" srcset=\"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/04\/Kayla-Harrison-1-1.webp?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/04\/Kayla-Harrison-1-1.webp?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/04\/Kayla-Harrison-1-1.webp?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/04\/Kayla-Harrison-1-1.webp?resize=555%2C370&amp;ssl=1 555w, https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2024\/04\/Kayla-Harrison-1-1.webp?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Kayla Harrison en el UFC 300. Cr\u00e9dito: Zuffa, LLC.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En la lista tambi\u00e9n destaca el ex-<strong>Bellator<\/strong> <strong>Michael Page<\/strong>, quien debut\u00f3 con una dominante victoria por decisi\u00f3n un\u00e1nime sobre <strong>Kevin Holland<\/strong> en el <strong>UFC 299<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;MVP&#8217; regres\u00f3 en el <strong>UFC 303<\/strong>, pero cay\u00f3 por una cerrado fallo un\u00e1nime contra <strong>Ian Garry<\/strong> en la pelea que abri\u00f3 el <em>Main Card<\/em>.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Kayla Harrison (1 &#8211; 0)<\/li>\n\n\n\n<li><strong>Vinicius Oliveira<\/strong> (2 &#8211; 0)<\/li>\n\n\n\n<li><strong>Felipe Lima <\/strong>(1 &#8211; 0)<\/li>\n\n\n\n<li><strong>Jean Silva<\/strong> (2 -0) y <strong>Carlos Prates<\/strong> (2 &#8211; 0)<\/li>\n\n\n\n<li>Michael Page (1 &#8211; 1)<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/x.com\/MMAalDia\"><strong>\u00a1Recuerden seguir a MMA al D\u00eda en X!<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Con la primera mitad de 2024 ya siendo cosa del pasado, UFC ha hecho una retrospectiva sobre los mejores debuts que tuvieron lugar sobre el oct\u00e1gono entre enero y junio. De los cinco atletas que fueron seleccionados, la organizaci\u00f3n estima que la judoca ol\u00edmpica Kayla Harrison tuvo el debut m\u00e1s impresionante de todos. La veterana [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,300,303],"tags":[2115,1875,434],"class_list":["post-33084","post","type-post","status-publish","format-standard","hentry","category-mma","category-noticias","category-noticias-de-mma","category-ufc","tag-kayla-harrison","tag-michael-page","tag-ufc"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/33084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=33084"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/33084\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=33084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=33084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=33084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}