{"id":23767,"date":"2023-11-15T11:42:15","date_gmt":"2023-11-15T16:42:15","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=23767"},"modified":"2023-11-15T11:42:15","modified_gmt":"2023-11-15T16:42:15","slug":"francis-ngannou-ingresa-al-top-10-de-la-wbc","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/francis-ngannou-ingresa-al-top-10-de-la-wbc\/","title":{"rendered":"Francis Ngannou ingresa al top 10 de la WBC"},"content":{"rendered":"<p>Pese a caer en su debut en el pugilismo profesional, <a href=\"\/es\/tag\/francis-ngannou\/\"><strong>Francis Ngannou<\/strong><\/a> ya consta como uno de los diez mejores Pesos Completos del planeta en los registros de la <strong>WBC<\/strong>.<\/p>\n<p>El excamp\u00f3n de <strong>UFC<\/strong> se estren\u00f3 en el boxeo el pasado 28 de octubre en Riad, Arabia Saudita, y aunque se desempe\u00f1\u00f3 mucho mejor de lo esperado, <a href=\"https:\/\/www.mmaaldia.com\/es\/tyson-fury-vence-a-francis-ngannou-con-polemica-decision-dividida\/\"><strong>perdi\u00f3 en las tarjetas contra Tyson Fury por un pol\u00e9mico fallo dividido<\/strong><\/a>.<\/p>\n<p>Dos semanas despu\u00e9s del combate, la WBC instal\u00f3 al camerun\u00e9s dentro de su ranking.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Francis Ngannou did an outstanding job against the WBC Heavyweight Champion and the WBC Board of Governors has agreed to rank him as No. 10 in the Heavyweight division.<a href=\"https:\/\/twitter.com\/FrancisNgannou?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@francisngannou<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/wbcboxing?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#wbcboxing<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/wbcuzbekistan23?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#wbcuzbekistan23<\/a> <a href=\"https:\/\/t.co\/mXjhiRS9Vt\">pic.twitter.com\/mXjhiRS9Vt<\/a><\/p>\n<p>&mdash; World Boxing Council (@WBCBoxing) <a href=\"https:\/\/twitter.com\/WBCBoxing\/status\/1724695241687810097?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">November 15, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>&#8220;Francis Ngannou hizo un notable trabajo contra el campe\u00f3n de Peso Completo de WBC, y es por eso que la junta de gobernadores de la WBC ha acordado clasificarlo como el n\u00famero 10 en la divisi\u00f3n de Peso Completo&#8221;.<\/p>\n<p>Ngannou firm\u00f3 con <strong>PFL<\/strong> a inicios de a\u00f1o para retomar su carrera en las MMA, pero lo m\u00e1s probable es que su pr\u00f3xima contienda sea con guantes de 10 onzas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Pese a caer en su debut en el pugilismo profesional, Francis Ngannou ya consta como uno de los diez mejores Pesos Completos del planeta en los registros de la WBC. El excamp\u00f3n de UFC se estren\u00f3 en el boxeo el pasado 28 de octubre en Riad, Arabia Saudita, y aunque se desempe\u00f1\u00f3 mucho mejor de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":23076,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[350,299],"tags":[379,1189],"class_list":["post-23767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxeo","category-noticias","tag-francis-ngannou","tag-wbc"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/10\/Tyson-Fury-2.webp?fit=1820%2C1213&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/23767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=23767"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/23767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/23076"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=23767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=23767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=23767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}