{"id":20630,"date":"2023-10-02T00:02:57","date_gmt":"2023-10-02T04:02:57","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=20630"},"modified":"2023-10-02T10:54:15","modified_gmt":"2023-10-02T14:54:15","slug":"laureano-staropoli-fala-sobre-sua-estreia-no-pfl","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/laureano-staropoli-fala-sobre-sua-estreia-no-pfl\/","title":{"rendered":"Laureano Staropoli fala sobre sua estreia no PFL: \u00abO amigo (Nadjombe) correu para todos os lados\u00bb"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A estreia do prospecto argentino <a href=\"https:\/\/www.mmaaldia.com\/es\/tag\/laureano-staropoli\/\"><strong>Laureano<\/strong> <strong>Staropoli<\/strong><\/a> (13 \u2013 5) na <a href=\"https:\/\/www.mmaaldia.com\/es\/tag\/pfl\/\"><strong>PFL<\/strong>\u00a0<\/a>foi um sucesso. Al\u00e9m disso, ele acumulou quatro vit\u00f3rias consecutivas em lutas profissionais.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">O ex-campe\u00e3o interino dos Meio-M\u00e9dios do <a href=\"https:\/\/www.mmaaldia.com\/es\/tag\/ares-fc\/\"><strong>Ares FC<\/strong><\/a> conseguiu uma vit\u00f3ria no <a href=\"https:\/\/www.mmaaldia.com\/es\/tag\/pfl-paris\/\"><strong>PFL Paris<\/strong><\/a> depois que <strong>Baba Nadjombe<\/strong> perdeu por TKO (interrup\u00e7\u00e3o do c\u00f3rner). O confronto entre eles foi em um Peso-Intermedi\u00e1rio de 180 libras.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Nas suas hist\u00f3rias do <a href=\"https:\/\/www.instagram.com\/pepilaureanocb\/?hl=es-la\" target=\"_blank\" rel=\"noopener\"><strong>Instagram<\/strong><\/a>, &#8216;Pepi&#8217; falou sobre a sua vit\u00f3ria e descreveu como foram as a\u00e7\u00f5es do combate:<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p class=\"wp-block-paragraph\">\u00abSoubemos resolver a luta porque o amigo (Nadjombe) correu para todos os lados. Eu calculo que o treinador dele disse &#8216;se cruzares com este, ele vai-te partir a cabe\u00e7a, ent\u00e3o corre e tenta acert\u00e1-lo com algum golpe&#8217;, mas n\u00e3o funcionou. Ele ficou cansado. No segundo round, trabalhei bem o corpo dele e o desgastei. Tirei-lhe a mobilidade com os golpes ao corpo. Conseguimos a primeira vit\u00f3ria no PFL. Obrigado a todos\u00bb<\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Staropoli foi um dos sul-americanos que participaram no evento que ocorreu no Zenith Paris &#8211; La Villette. Al\u00e9m dele, estiveram presentes a colombiana <strong>Luisa Cifuentes<\/strong> e o brasileiro <strong>Henrique Madureira<\/strong>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Conhe\u00e7a aqui os <a href=\"https:\/\/www.mmaaldia.com\/es\/resultados-del-pfl-paris-doumbe-impresiona-en-pfl\/\"><strong>resultados de todas as lutas do PFL Paris<\/strong>:<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A estreia do prospecto argentino Laureano Staropoli (13 \u2013 5) na PFL\u00a0foi um sucesso. Al\u00e9m disso, ele acumulou quatro vit\u00f3rias consecutivas em lutas profissionais.\u00a0 O ex-campe\u00e3o interino dos Meio-M\u00e9dios do Ares FC conseguiu uma vit\u00f3ria no PFL Paris depois que Baba Nadjombe perdeu por TKO (interrup\u00e7\u00e3o do c\u00f3rner). O confronto entre eles foi em um [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":20579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[299],"tags":[1859,588,1816],"class_list":["post-20630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-laureano-staropoli","tag-pfl","tag-pfl-paris"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/10\/Laureano-Staropoli.webp?fit=1220%2C813&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/20630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=20630"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/20630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/20579"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=20630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=20630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=20630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}