{"id":16811,"date":"2023-08-27T14:37:15","date_gmt":"2023-08-27T18:37:15","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=16811"},"modified":"2023-08-27T14:37:15","modified_gmt":"2023-08-27T18:37:15","slug":"masvidal-acepta-revancha-con-askren-en-el-boxeo","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/masvidal-acepta-revancha-con-askren-en-el-boxeo\/","title":{"rendered":"Masvidal acepta revancha con Askren, pero no en MMA: &#8220;En el boxeo no hay rodillazos, imb\u00e9cil&#8221;"},"content":{"rendered":"<p>Si <a href=\"\/es\/tag\/ben-askren\/\"><strong>Ben Askren<\/strong><\/a> quiere una revancha con <a href=\"\/es\/tag\/jorge-masvidal\/\"><strong>Jorge Masvidal<\/strong><\/a>, entonces deber\u00e1 volver a enfundarse los guantes de boxeo.<\/p>\n<p>Masvidal, retirado de las MMA en abril del presente a\u00f1o, acept\u00f3 la propuesta a una revancha del excampe\u00f3n de <strong>Bellator<\/strong> , pero en un cuadril\u00e1tero<\/p>\n<p>&#8220;\u00bfEste tipo sigue hablando m&#8230;.., hermano?, pregunt\u00f3 Masvidal durante una entrevista con <a href=\"https:\/\/www.mmamania.com\/2023\/8\/27\/23847607\/jorge-masvidal-rips-coward-ben-askren-for-wanting-mma-rematch-hes-fucking-brain-dead\" target=\"_blank\" rel=\"noopener\"><strong>MMA Mania<\/strong><\/a>. &#8220;Este tipo es un maldito idiota. Escucha, ese rodillazo lo mat\u00f3 cerebralmente. Estoy retirado de las MMA, maldito idiota. En el boxeo no hay rodillazos, imb\u00e9cil. As\u00ed que ac\u00e9rcate y conseguiremos a alguien para que te firme un jodido buen cheque para que te vuelva a aplastar la cabeza y puedas hacer el doble de lo que has ganado en toda tu carrera. Pero como es un cobarde, no lo har\u00e1&#8221;.<\/p>\n<p>Askren, quien colg\u00f3 los guantes a finales de 2019, ha mostrado inter\u00e9s en pelear siempre y cuando sea ante Masvidal.<\/p>\n<p>El cubano protagoniz\u00f3 el nocaut m\u00e1s r\u00e1pido (00:05) en toda la historia de UFC al noquear a Askren de un rodillazo volador en el <strong>UFC 239<\/strong>.<\/p>\n<p><strong>Askren, ahora de 39 a\u00f1os, cuenta con una sola disputa en el pugilismo profesional: una derrota por TKO en el segundo round ante Jake Paul en abril de 2021<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Si Ben Askren quiere una revancha con Jorge Masvidal, entonces deber\u00e1 volver a enfundarse los guantes de boxeo. Masvidal, retirado de las MMA en abril del presente a\u00f1o, acept\u00f3 la propuesta a una revancha del excampe\u00f3n de Bellator , pero en un cuadril\u00e1tero &#8220;\u00bfEste tipo sigue hablando m&#8230;.., hermano?, pregunt\u00f3 Masvidal durante una entrevista con [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":16812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[350,296,299],"tags":[734,540],"class_list":["post-16811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxeo","category-mma","category-noticias","tag-ben-askren","tag-jorge-masvidal"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/08\/Jorge-Masvidal-scaled.webp?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/16811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=16811"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/16811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/16812"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=16811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=16811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=16811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}