{"id":14033,"date":"2023-07-13T16:38:19","date_gmt":"2023-07-13T20:38:19","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=14033"},"modified":"2023-07-13T16:39:18","modified_gmt":"2023-07-13T20:39:18","slug":"devin-haney-es-arrestado-por-presunta-arma-semiautomatica-encontrada-bajo-su-poder","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/devin-haney-es-arrestado-por-presunta-arma-semiautomatica-encontrada-bajo-su-poder\/","title":{"rendered":"Devin Haney es arrestado por presunta arma semiautom\u00e1tica encontrada &#8220;bajo su poder&#8221;"},"content":{"rendered":"<p><a href=\"\/es\/tag\/Devin-Haney\/\"><strong>Devin Haney<\/strong><\/a>, fue recientemente puesto bajo custodia y acusado de un delito grave por llevar un arma oculta en Los \u00c1ngeles, California.<\/p>\n<p>Seg\u00fan informes recientes de TMZ Sports, el campe\u00f3n de boxeo de peso ligero fue detenido la madrugada del jueves. El incidente se produjo luego de una noche de fiesta, durante la cual las fuerzas del orden detuvieron a Haney y a sus amigos en un control de tr\u00e1fico rutinario.<\/p>\n<p>Y aunque Haney no iba al volante, el conductor, cuya identidad no ha sido revelada, inform\u00f3 a la polic\u00eda de la presencia de un arma de fuego en el veh\u00edculo. Posteriormente, se descubri\u00f3 una pistola semiautom\u00e1tica debajo del asiento del conductor durante un registro rutinario.<\/p>\n<p>Haney fue detenido, pero qued\u00f3 en libertad tras pagar una fianza de 35.000 d\u00f3lares. El californiano, de 24 a\u00f1os, deber\u00e1 comparecer ante el tribunal el mes que viene.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Boxing Star Devin Haney Arrested, Semi-Automatic Gun Allegedly Found In Car <a href=\"https:\/\/t.co\/YgLK450AVJ\">https:\/\/t.co\/YgLK450AVJ<\/a><\/p>\n<p>\u2014 TMZ Sports (@TMZ_Sports) <a href=\"https:\/\/twitter.com\/TMZ_Sports\/status\/1679521677179273218?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 13, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>","protected":false},"excerpt":{"rendered":"<p>Devin Haney, fue recientemente puesto bajo custodia y acusado de un delito grave por llevar un arma oculta en Los \u00c1ngeles, California. Seg\u00fan informes recientes de TMZ Sports, el campe\u00f3n de boxeo de peso ligero fue detenido la madrugada del jueves. El incidente se produjo luego de una noche de fiesta, durante la cual las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[350],"tags":[314,1414],"class_list":["post-14033","post","type-post","status-publish","format-standard","hentry","category-boxeo","tag-boxeo","tag-devin-haney"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/14033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=14033"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/14033\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=14033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=14033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=14033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}