{"id":11199,"date":"2023-05-31T08:35:24","date_gmt":"2023-05-31T12:35:24","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=11199"},"modified":"2023-05-31T08:35:24","modified_gmt":"2023-05-31T12:35:24","slug":"video-mcgregor-derrocha-dinero-comprando-su-propia-figura-de-accion-a-un-nino","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/video-mcgregor-derrocha-dinero-comprando-su-propia-figura-de-accion-a-un-nino\/","title":{"rendered":"Video: McGregor derrocha dinero comprando su propia figura de acci\u00f3n a un ni\u00f1o"},"content":{"rendered":"<p><span>El primer episodio de la temporada 31 de\u00a0<\/span><em><span>The Ultimate Fighter,<\/span><\/em><span>\u00a0protagonizado por <strong>Conor McGregor<\/strong> y <a href=\"\/es\/tag\/Michael-Chandler\/\"><strong>Michael Chandler<\/strong><\/a> como entrenadores del equipo contrario, se emiti\u00f3 recientemente en UFC Fight Pass.<\/span><\/p>\n<p><span>En un clip del primer episodio, se ve a McGregor complaci\u00e9ndose derrochando en una figura de acci\u00f3n de s\u00ed mismo.\u00a0En el segmento, est\u00e1 sentado con un ni\u00f1o, que presumiblemente es el due\u00f1o de la figura de acci\u00f3n, y se ofrece a comprarla.<\/span><\/p>\n<p><span>Antes de que<strong> &#8216;The Notorious&#8217;<\/strong> reciba una respuesta, ya sac\u00f3 un fajo de billetes y sac\u00f3 algo para d\u00e1rselo al ni\u00f1o.\u00a0McGregor dice en el clip:<\/span><\/p>\n<blockquote><p>&#8220;Te las quitar\u00e9 todas, t\u00edo, \u00bfvale? Te quitar\u00e9 estas, chico. S\u00f3lo 12 toneladas, \u00bfs\u00ed? 12 toneladas, mi hombre. Hehe.&#8221;<\/p><\/blockquote>\n<p><em><span>Mira el clip de McGregor compr\u00e1ndole una figura de acci\u00f3n de s\u00ed mismo a un ni\u00f1o:<\/span><\/em><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">TUF 31 <a href=\"https:\/\/twitter.com\/TheNotoriousMMA?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@TheNotoriousMMA<\/a> just gave this kid some cash in exchange for his own Action Figure. LEGENDARY <a href=\"https:\/\/twitter.com\/hashtag\/TUF31?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#TUF31<\/a> <a href=\"https:\/\/t.co\/QiXs3qqgBY\">pic.twitter.com\/QiXs3qqgBY<\/a><\/p>\n<p>&mdash; UpperKut \ud83d\udca5\ud83e\uddbe (@KalyanMMA) <a href=\"https:\/\/twitter.com\/KalyanMMA\/status\/1663743038093508609?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 31, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><span>La cantidad exacta que pag\u00f3 Conor McGregor no est\u00e1 clara, pero menciona que le dio &#8217;12 toneladas&#8217; al ni\u00f1o, lo que podr\u00eda ascender a $ 1,200, ya que la tonelada es la jerga brit\u00e1nica para cien.\u00a0Una\u00a0<\/span><span>figura de acci\u00f3n similar de McGregor<\/span><span>\u00a0est\u00e1 disponible en la<strong>\u00a0<\/strong><\/span><strong><a href=\"https:\/\/ufcstore.com\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" data-is-sponsored=\"false\">tienda de UFC<\/a><\/strong><span><strong>\u00a0<\/strong>por $25 y tambi\u00e9n est\u00e1 disponible en Amazon por $36.<\/span><\/p>\n<p><span>El clip no tiene ning\u00fan contexto en el episodio y tampoco se revela la identidad del ni\u00f1o.\u00a0Apareci\u00f3 hacia el final del episodio y podr\u00eda ser una vista previa del episodio de la pr\u00f3xima semana.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>El primer episodio de la temporada 31 de\u00a0The Ultimate Fighter,\u00a0protagonizado por Conor McGregor y Michael Chandler como entrenadores del equipo contrario, se emiti\u00f3 recientemente en UFC Fight Pass. En un clip del primer episodio, se ve a McGregor complaci\u00e9ndose derrochando en una figura de acci\u00f3n de s\u00ed mismo.\u00a0En el segmento, est\u00e1 sentado con un ni\u00f1o, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[303,301],"tags":[319,525],"class_list":["post-11199","post","type-post","status-publish","format-standard","hentry","category-ufc","category-videos","tag-conor-mcgregor","tag-michael-chandler"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/11199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=11199"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/11199\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=11199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=11199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=11199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}