{"id":10684,"date":"2023-05-25T14:14:25","date_gmt":"2023-05-25T18:14:25","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=10684"},"modified":"2023-05-25T14:14:25","modified_gmt":"2023-05-25T18:14:25","slug":"presidente-de-pfl-descarta-pelea-entre-francis-ngannou-y-fabricio-werdum","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/presidente-de-pfl-descarta-pelea-entre-francis-ngannou-y-fabricio-werdum\/","title":{"rendered":"Presidente de PFL descarta pelea entre Francis Ngannou y Fabricio Werdum"},"content":{"rendered":"<p>Cuando se trata del debut de <a href=\"\/es\/tag\/francis-ngannou\/\"><strong>Francis Ngannou<\/strong><\/a>, <a href=\"\/es\/tag\/pfl\/\"><strong>PFL<\/strong><\/a> tiene planes &#8220;m\u00e1s grandes&#8221; que una pelea con <strong>Fabricio Werdum<\/strong>.<\/p>\n<p>Invitado en el podcast de Barstool Sports, <em><a href=\"https:\/\/www.youtube.com\/watch?v=H5wr8nd32pM\" target=\"_blank\" rel=\"noopener\"><strong>My Mom&#8217;s Basement<\/strong><\/a><\/em>, <strong>Donn Davis<\/strong>, fundador de PFL, explic\u00f3 qu\u00e9 preparan para el anticipado debut del africano en 2024.<\/p>\n<p>&#8220;Hubo todo tipo de especulaci\u00f3n, variando desde el formato de la temporada de PFL hasta (Fabricio) Werdum&#8221;, explic\u00f3 (transcripci\u00f3n amabilidad de <a href=\"https:\/\/agfight.com\/pfl\/dirigente-da-pfl-minimiza-possibilidade-de-realizar-werdum-vs-ngannou-algo-maior\/\" target=\"_blank\" rel=\"noopener\"><strong>Ag. Fight<\/strong><\/a>). &#8220;Creo que ser\u00e1 algo diferente, algo m\u00e1s grande y llamativo de lo que se ha le\u00eddo hasta ahora. Tenemos nueve meses. Hace nueve meses las personas se re\u00edan cuando dec\u00edamos que Ngannou ven\u00eda a PFL. Entonces, si yo fuese a especular ahora, las personas dir\u00edan, &#8216;eso nunca va a pasar&#8217;. Crean. No duden de nuestra creatividad&#8221;.<\/p>\n<p>Antes que Ngannou se enfunde los guantes de PFL, el camerun\u00e9s primero disputar\u00e1 una contienda de boxeo en lo que resta de este a\u00f1o.<\/p>\n<p><a href=\"https:\/\/www.mmaaldia.com\/es\/fabricio-werdum-desafia-a-francis-ngannou-para-combate-en-pfl\/\"><strong>Werdum, por su parte, hab\u00eda manifestado su deseo de enfrentar al ex-campe\u00f3n de UFC en Brasil<\/strong><\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cuando se trata del debut de Francis Ngannou, PFL tiene planes &#8220;m\u00e1s grandes&#8221; que una pelea con Fabricio Werdum. Invitado en el podcast de Barstool Sports, My Mom&#8217;s Basement, Donn Davis, fundador de PFL, explic\u00f3 qu\u00e9 preparan para el anticipado debut del africano en 2024. &#8220;Hubo todo tipo de especulaci\u00f3n, variando desde el formato de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":10686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[296,299,320],"tags":[1295,379],"class_list":["post-10684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mma","category-noticias","category-pfl","tag-fabricio-werdum","tag-francis-ngannou"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mmaaldia.com\/wp-content\/uploads\/2023\/05\/Francis-Ngannou.webp?fit=1200%2C900&ssl=1","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/10684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=10684"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/10684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media\/10686"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=10684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=10684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=10684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}