{"id":10357,"date":"2023-05-21T12:15:06","date_gmt":"2023-05-21T16:15:06","guid":{"rendered":"https:\/\/www.mmaaldia.com\/?p=10357"},"modified":"2023-05-21T12:15:06","modified_gmt":"2023-05-21T16:15:06","slug":"quien-es-dave-moretti-juez-de-boxeo-se-vuelve-viral-por-su-absurda-puntuacion-en-la-pelea-de-devin-haney","status":"publish","type":"post","link":"https:\/\/www.mmaaldia.com\/es\/quien-es-dave-moretti-juez-de-boxeo-se-vuelve-viral-por-su-absurda-puntuacion-en-la-pelea-de-devin-haney\/","title":{"rendered":"Juez de boxeo se vuelve viral por su absurda puntuaci\u00f3n en la pelea de Devin Haney"},"content":{"rendered":"<p><strong>Dave Moretti<\/strong> es un juez de boxeo estadounidense que lleva puntuando combates desde 1977. Con una dilatada experiencia en este deporte, Moretti ha arbitrado m\u00e1s de 90 combates por el t\u00edtulo mundial. Sin embargo, el nativo de Las Vegas ha sido recientemente objeto de escrutinio por parte de los aficionados al boxeo de todo el mundo por su arbitraje durante el combate entre <a href=\"\/es\/tag\/Devin-Haney\/\"><strong>Devin Haney<\/strong><\/a> y <a href=\"\/es\/tag\/Vasiliy-Lomachenko\/\"><strong>Vasiliy Lomachenko<\/strong><\/a>.<\/p>\n<p>Haney y Lomachenko se enfrentaron anoche en el MGM Garden Arena de Las Vegas, Nevada. El esperado combate por el t\u00edtulo indiscutible del peso ligero result\u00f3 mucho m\u00e1s re\u00f1ido de lo que todos esperaban y, a pesar de que Lomachenko part\u00eda como no favorito, se mostr\u00f3 como el mejor peleador.<\/p>\n<p>En un resultado que sorprendi\u00f3 a la mayor\u00eda del mundo del boxeo, Devin Haney retuvo su t\u00edtulo de campe\u00f3n indiscutible del peso ligero por decisi\u00f3n un\u00e1nime (115-113, 115-113, 116-112). Sin embargo, no son las tarjetas de puntuaci\u00f3n general las que m\u00e1s han escarnecido a los aficionados al boxeo.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Devin Haney UD Vasyl Lomachenko official judges&#39; scorecards\u2026 <a href=\"https:\/\/t.co\/eBXqMXVXYC\">pic.twitter.com\/eBXqMXVXYC<\/a><\/p>\n<p>&mdash; Michael Benson (@MichaelBensonn) <a href=\"https:\/\/twitter.com\/MichaelBensonn\/status\/1660147815073341442?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">May 21, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Moretti, uno de los jueces del combate, puntu\u00f3 el 10\u00ba asalto a favor de Haney a pesar de que Lomachenko domin\u00f3 el asalto de principio a fin. Adem\u00e1s, tambi\u00e9n fue uno de los asaltos m\u00e1s dominados por cualquiera de los dos durante todo el combate.<\/p>\n<p>ECHA UN VISTAZO:\u00a0<a href=\"https:\/\/www.mmaaldia.com\/es\/bonos-del-ufc-vegas-73-borshchev-y-ferreira-premiados-por-desempeno-dern-y-hill-por-pelea-de-la-noche\/\" target=\"_blank\" rel=\"noopener\">Bonos del UFC Vegas 73: Borshchev y Ferreira premiados por desempe\u00f1o; Dern y Hill por Pelea de la Noche<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dave Moretti es un juez de boxeo estadounidense que lleva puntuando combates desde 1977. Con una dilatada experiencia en este deporte, Moretti ha arbitrado m\u00e1s de 90 combates por el t\u00edtulo mundial. Sin embargo, el nativo de Las Vegas ha sido recientemente objeto de escrutinio por parte de los aficionados al boxeo de todo el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[350],"tags":[314,1414,1415],"class_list":["post-10357","post","type-post","status-publish","format-standard","hentry","category-boxeo","tag-boxeo","tag-devin-haney","tag-vasiliy-lomachenko"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/10357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/comments?post=10357"}],"version-history":[{"count":0,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/posts\/10357\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/media?parent=10357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/categories?post=10357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mmaaldia.com\/es\/wp-json\/wp\/v2\/tags?post=10357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}